
{"id":35,"date":"2022-06-09T01:58:19","date_gmt":"2022-06-09T01:58:27","guid":{"rendered":"https:\/\/stgschoolcraft.wpengine.com\/fitness-center\/?page_id=35"},"modified":"2023-02-14T19:12:08","modified_gmt":"2023-02-14T19:12:08","slug":"cardio-equipment","status":"publish","type":"page","link":"https:\/\/www.schoolcraft.edu\/fitness-center\/facilities\/cardio-equipment\/","title":{"rendered":"Cardio Equipment"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Cardio Equipment<\/h1>\n\n\n\n<div style=\"color:#ddd\" class=\"wp-block-genesis-blocks-gb-spacer gb-block-spacer gb-divider-solid gb-spacer-divider gb-divider-size-1\"><hr style=\"height:30px\"\/><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Precor\u00ae treadmills, ellipticals, bikes and Adaptive Motion Trainers (AMT&#8217;s) featuring individual entertainment consoles<\/li>\n\n\n\n<li>Woodway Curve\u00ae &nbsp;manual treadmills<\/li>\n\n\n\n<li>Stairmaster\u00ae Stepmills<\/li>\n\n\n\n<li>Concept 2\u00ae Rowers<\/li>\n\n\n\n<li>Expresso\u00ae interactive bikes\u00a0<\/li>\n\n\n\n<li>The Echelon\u2122 Smart Connect Bikes<\/li>\n\n\n\n<li>Jacob\u2019s Ladder\u2122<\/li>\n\n\n\n<li>NuStep\u00ae<\/li>\n\n\n\n<li>Sci-Fit Seated Upper Body Ergometer&nbsp;<\/li>\n\n\n\n<li>Helix Lateral Trainer\u2122<\/li>\n\n\n\n<li>Spirit Air Bikes<\/li>\n\n\n\n<li>VersaClimber<\/li>\n<\/ul>\n\n\n\n<div style=\"height:75px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns gb-layout-columns-3 gb-3-col-equal\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!4v1574366377561!6m8!1m7!1sCAoSK0FGMVFpcE1aei1yTWc0NDZoZW5fekxybHVxOVNBWURFUmV2eGFyVTV1aFk.!2m2!1d42.4191344!2d-83.4278899!3f120!4f0!5f0.7820865974627469\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0; border-radius: 12px;\" allowfullscreen=\"\"><\/iframe>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!4v1574369017057!6m8!1m7!1sCAoSK0FGMVFpcE81NnoySEdvTWRsdkU5NVFJa21UQUc2QzcwZUQ4NXNpOWc2Sms.!2m2!1d42.4191344!2d-83.4278899!3f140!4f0!5f0.7820865974627469\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0; border-radius: 12px;\" allowfullscreen=\"\"><\/iframe>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!4v1574369483182!6m8!1m7!1sCAoSK0FGMVFpcE1Wd3I1Yzk3amFsZHVqQ3ZscXU1bGs0XzBySUxPM3BGZ0dvcEU.!2m2!1d42.4191344!2d-83.4278899!3f60!4f20!5f0.7820865974627469\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0; border-radius: 12px;\" allowfullscreen=\"\"><\/iframe>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cardio Equipment<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":31,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/sc-full-width.php","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"full-width-content","footnotes":""},"class_list":["post-35","page","type-page","status-publish","entry"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/pages\/31"}],"wp:attachment":[{"href":"https:\/\/www.schoolcraft.edu\/fitness-center\/wp-json\/wp\/v2\/media?parent=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}